{"id":2478,"date":"2024-11-19T09:59:48","date_gmt":"2024-11-19T12:59:48","guid":{"rendered":"https:\/\/noupwind.com\/questions\/est-il-necessaire-de-parler-portugais-pour-voyager-au-bresil\/"},"modified":"2024-11-23T13:48:20","modified_gmt":"2024-11-23T16:48:20","slug":"est-il-necessaire-de-parler-portugais-pour-voyager-au-bresil","status":"publish","type":"questions","link":"https:\/\/noupwind.com\/fr\/questions\/est-il-necessaire-de-parler-portugais-pour-voyager-au-bresil\/","title":{"rendered":"Est-il n\u00e9cessaire de parler portugais pour voyager au Br\u00e9sil ?"},"content":{"rendered":"\n<p>Ce n&rsquo;est pas obligatoire, mais cela peut \u00eatre utile. Dans les zones touristiques et de kitesurf, de nombreuses personnes parlent anglais, et nos guides et instructeurs sont bilingues. Si vous \u00eates pr\u00e9occup\u00e9, nous pouvons vous assister tout au long de votre s\u00e9jour avec un guide qui parle votre langue.  <\/p>\n","protected":false},"template":"","class_list":["post-2478","questions","type-questions","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/noupwind.com\/fr\/wp-json\/wp\/v2\/questions\/2478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noupwind.com\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/noupwind.com\/fr\/wp-json\/wp\/v2\/types\/questions"}],"wp:attachment":[{"href":"https:\/\/noupwind.com\/fr\/wp-json\/wp\/v2\/media?parent=2478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}