{"id":2765,"date":"2025-02-06T14:13:06","date_gmt":"2025-02-06T17:13:06","guid":{"rendered":"https:\/\/noupwind.com\/kitetrips\/amazon-wing-foil-expedition-exclusive-water-adventure\/"},"modified":"2025-02-06T14:21:01","modified_gmt":"2025-02-06T17:21:01","slug":"amazon-wing-foil-expedition-exclusive-water-adventure","status":"publish","type":"kitetrips","link":"https:\/\/noupwind.com\/es\/kitetrips\/amazon-wing-foil-expedition-exclusive-water-adventure\/","title":{"rendered":"Expedici\u00f3n de Wing Foil en el Amazonas \u2013 Aventura Acu\u00e1tica Exclusiva"},"content":{"rendered":"\n<p><strong>D\u00eda 1: <\/strong>Llegada a Santar\u00e9m y traslado a su casa flotante. Tan pronto como se embarque, zarparemos hacia los afluentes del Amazonas, navegando a trav\u00e9s de paisajes v\u00edrgenes, lejos de las rutas habituales.<\/p>\n\n<p><strong>A lo largo del viaje:<\/strong> Cada d\u00eda trae consigo una nueva exploraci\u00f3n. Tan pronto como el viento se intensifique, ser\u00e1 el momento de emocionantes sesiones de wing foil en aguas salvajes, rodeados por la selva amaz\u00f3nica. Entre sesiones, sum\u00e9rjase en las comunidades locales, explore la jungla y descubra la extraordinaria biodiversidad de este ecosistema \u00fanico.<\/p>\n\n<p>Fin del viaje: Dependiendo de la duraci\u00f3n que elija, regreso a tierra firme y traslado al aeropuerto de Santar\u00e9m. Para los interesados, se puede agregar un d\u00eda opcional para explorar la ciudad.<\/p>\n\n<p>Dos formatos de experiencia disponibles:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Alojamiento en una casa flotante para una experiencia completamente inmersiva<\/li>\n\n\n\n<li> Alojamiento en tierra con salidas diarias en barco para navegar en los r\u00edos del Amazonas<\/li>\n<\/ul>\n\n<p>\u00a1Una aventura \u00fanica en su tipo, que combina adrenalina y naturaleza en estado puro!<br\/><a href=\"https:\/\/noupwind.com\/es\/ponte-en-contacto-con\/\" data-type=\"page\" data-id=\"51\">\u00a1Cont\u00e1ctenos para obtener m\u00e1s informaci\u00f3n!<\/a><\/p>\n","protected":false},"featured_media":2755,"template":"","class_list":["post-2765","kitetrips","type-kitetrips","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/noupwind.com\/es\/wp-json\/wp\/v2\/kitetrips\/2765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noupwind.com\/es\/wp-json\/wp\/v2\/kitetrips"}],"about":[{"href":"https:\/\/noupwind.com\/es\/wp-json\/wp\/v2\/types\/kitetrips"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noupwind.com\/es\/wp-json\/wp\/v2\/media\/2755"}],"wp:attachment":[{"href":"https:\/\/noupwind.com\/es\/wp-json\/wp\/v2\/media?parent=2765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}